{"id":24857,"date":"2025-05-08T15:27:56","date_gmt":"2025-05-08T12:27:56","guid":{"rendered":"https:\/\/academy.police.md\/?p=24857"},"modified":"2025-05-08T15:29:30","modified_gmt":"2025-05-08T12:29:30","slug":"reinstalarea-basoreliefului-domnitorului-stefan-cel-mare-intre-memorie-si-identitate-institutionala","status":"publish","type":"post","link":"https:\/\/www.academy.police.md\/gb\/reinstalarea-basoreliefului-domnitorului-stefan-cel-mare-intre-memorie-si-identitate-institutionala","title":{"rendered":"Reinstalarea basoreliefului domnitorului \u0218tefan cel Mare \u2013 \u00eentre memorie \u0219i identitate institu\u021bional\u0103"},"content":{"rendered":"\n<p>La 26 de ani de la prima dezvelire, basorelieful domnitorului \u0218tefan cel Mare \u0219i Sf\u00e2nt \u00ee\u0219i reg\u0103se\u0219te locul de onoare \u00een cadrul Academiei \u201e\u0218tefan cel Mare\u201d a MAI \u2013 o re\u00eentoarcere simbolic\u0103 \u00een centrul memoriei \u0219i identit\u0103\u021bii institu\u021bionale.<\/p>\n\n\n\n<p>Lucrarea a fost d\u0103ruit\u0103 institu\u021biei \u00een anul 1999 de c\u0103tre absolven\u021bii promo\u021biei a IV-a (seria 1994\u20131999), \u00een semn de recuno\u0219tin\u021b\u0103 \u0219i loialitate fa\u021b\u0103 de valorile formate pe parcursul anilor de studii. Monumentul a fost inaugurat pentru prima dat\u0103 pe 8 mai 1999, \u00een ziua ceremoniei de absolvire, fiind amplasat \u00een spa\u021biul public, \u00een fa\u021ba intr\u0103rii principale a Academiei.<\/p>\n\n\n\n<p>\u00cen anul 2022, \u00een contextul unor lucr\u0103ri de reabilitare a teritoriului, basorelieful a fost temporar retras \u0219i p\u0103strat &nbsp;\u00een muzeul institu\u021biei. Ast\u0103zi, la exact 26 de ani de la dezvelirea ini\u021bial\u0103, acesta revine la locul s\u0103u de onoare, \u00een acord cu identitatea \u0219i memoria institu\u021bional\u0103 a Academiei.<\/p>\n\n\n\n<p>Lucrarea poart\u0103 semn\u0103tura sculptorului Valentin Cuzne\u021bov (1933\u20132005), artist consacrat, autor \u0219i al autoreliefului lui Ion Creang\u0103, amplasat pe fa\u021bada Universit\u0103\u021bii Pedagogice din Chi\u0219in\u0103u. Prin aceast\u0103 crea\u021bie, valorile de curaj, credin\u021b\u0103 \u0219i demnitate r\u0103m\u00e2n ancorate \u00een cultura institu\u021bional\u0103 \u0219i vor \u00eenso\u021bi, \u00een mod simbolic, formarea noilor genera\u021bii de studen\u021bi \u0219i cadre.<\/p>\n\n\n\n<p>Una dintre metodele de educa\u0163ie militaro-patriotic\u0103 \u015fi istorico-cultural\u0103 a tinerei genera\u0163ii este&nbsp; amplasarea \u00een spa\u0163iile academice a chipurilor personalit\u0103\u0163ilor notorii care au l\u0103sat urme proeminente \u00een istoria neamului nostru (picturi, tablouri, busturi, basoreliefuri, monumente etc.).<\/p>\n\n\n\n<p>Evenimentul redeschiderii marcheaz\u0103 nu doar o restaurare fizic\u0103, ci \u0219i o reafirmare a leg\u0103turii profunde dintre tradi\u021bie, educa\u021bie \u0219i spiritul de slujire public\u0103.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2025\/05\/1V3A6777_DxO-1024x683.jpg\" alt=\"\" data-id=\"24859\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/1V3A6777_DxO-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=24859\" class=\"wp-image-24859\" srcset=\"\/wp-content\/uploads\/2025\/05\/1V3A6777_DxO-1024x683.jpg 1024w, \/wp-content\/uploads\/2025\/05\/1V3A6777_DxO-300x200.jpg 300w, \/wp-content\/uploads\/2025\/05\/1V3A6777_DxO-768x512.jpg 768w, \/wp-content\/uploads\/2025\/05\/1V3A6777_DxO-1536x1024.jpg 1536w, \/wp-content\/uploads\/2025\/05\/1V3A6777_DxO-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2025\/05\/1V3A6780_DxO-1024x683.jpg\" alt=\"\" data-id=\"24860\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/1V3A6780_DxO-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=24860\" class=\"wp-image-24860\" srcset=\"\/wp-content\/uploads\/2025\/05\/1V3A6780_DxO-1024x683.jpg 1024w, \/wp-content\/uploads\/2025\/05\/1V3A6780_DxO-300x200.jpg 300w, \/wp-content\/uploads\/2025\/05\/1V3A6780_DxO-768x512.jpg 768w, \/wp-content\/uploads\/2025\/05\/1V3A6780_DxO-1536x1024.jpg 1536w, \/wp-content\/uploads\/2025\/05\/1V3A6780_DxO-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"677\" src=\"\/wp-content\/uploads\/2025\/05\/1V3A6787_DxO-1024x677.jpg\" alt=\"\" data-id=\"24861\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/1V3A6787_DxO-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=24861\" class=\"wp-image-24861\" srcset=\"\/wp-content\/uploads\/2025\/05\/1V3A6787_DxO-1024x677.jpg 1024w, \/wp-content\/uploads\/2025\/05\/1V3A6787_DxO-300x198.jpg 300w, \/wp-content\/uploads\/2025\/05\/1V3A6787_DxO-768x508.jpg 768w, \/wp-content\/uploads\/2025\/05\/1V3A6787_DxO-1536x1016.jpg 1536w, \/wp-content\/uploads\/2025\/05\/1V3A6787_DxO-2048x1354.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2025\/05\/1V3A6789_DxO-1024x683.jpg\" alt=\"\" data-id=\"24862\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/1V3A6789_DxO-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=24862\" class=\"wp-image-24862\" srcset=\"\/wp-content\/uploads\/2025\/05\/1V3A6789_DxO-1024x683.jpg 1024w, \/wp-content\/uploads\/2025\/05\/1V3A6789_DxO-300x200.jpg 300w, \/wp-content\/uploads\/2025\/05\/1V3A6789_DxO-768x512.jpg 768w, \/wp-content\/uploads\/2025\/05\/1V3A6789_DxO-1536x1024.jpg 1536w, \/wp-content\/uploads\/2025\/05\/1V3A6789_DxO-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2025\/05\/1V3A6791_DxO-1024x683.jpg\" alt=\"\" data-id=\"24863\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/1V3A6791_DxO-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=24863\" class=\"wp-image-24863\" srcset=\"\/wp-content\/uploads\/2025\/05\/1V3A6791_DxO-1024x683.jpg 1024w, \/wp-content\/uploads\/2025\/05\/1V3A6791_DxO-300x200.jpg 300w, \/wp-content\/uploads\/2025\/05\/1V3A6791_DxO-768x512.jpg 768w, \/wp-content\/uploads\/2025\/05\/1V3A6791_DxO-1536x1024.jpg 1536w, \/wp-content\/uploads\/2025\/05\/1V3A6791_DxO-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2025\/05\/1V3A6795_DxO-1024x683.jpg\" alt=\"\" data-id=\"24864\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/1V3A6795_DxO-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=24864\" class=\"wp-image-24864\" srcset=\"\/wp-content\/uploads\/2025\/05\/1V3A6795_DxO-1024x683.jpg 1024w, \/wp-content\/uploads\/2025\/05\/1V3A6795_DxO-300x200.jpg 300w, \/wp-content\/uploads\/2025\/05\/1V3A6795_DxO-768x512.jpg 768w, \/wp-content\/uploads\/2025\/05\/1V3A6795_DxO-1536x1024.jpg 1536w, \/wp-content\/uploads\/2025\/05\/1V3A6795_DxO-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2025\/05\/1V3A6796_DxO-1024x683.jpg\" alt=\"\" data-id=\"24865\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/1V3A6796_DxO-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=24865\" class=\"wp-image-24865\" srcset=\"\/wp-content\/uploads\/2025\/05\/1V3A6796_DxO-1024x683.jpg 1024w, \/wp-content\/uploads\/2025\/05\/1V3A6796_DxO-300x200.jpg 300w, \/wp-content\/uploads\/2025\/05\/1V3A6796_DxO-768x512.jpg 768w, \/wp-content\/uploads\/2025\/05\/1V3A6796_DxO-1536x1024.jpg 1536w, \/wp-content\/uploads\/2025\/05\/1V3A6796_DxO-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2025\/05\/1V3A6798_DxO-1024x683.jpg\" alt=\"\" data-id=\"24866\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/1V3A6798_DxO-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=24866\" class=\"wp-image-24866\" srcset=\"\/wp-content\/uploads\/2025\/05\/1V3A6798_DxO-1024x683.jpg 1024w, \/wp-content\/uploads\/2025\/05\/1V3A6798_DxO-300x200.jpg 300w, \/wp-content\/uploads\/2025\/05\/1V3A6798_DxO-768x512.jpg 768w, \/wp-content\/uploads\/2025\/05\/1V3A6798_DxO-1536x1024.jpg 1536w, \/wp-content\/uploads\/2025\/05\/1V3A6798_DxO-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2025\/05\/1V3A6800_DxO-1024x683.jpg\" alt=\"\" data-id=\"24867\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/1V3A6800_DxO-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=24867\" class=\"wp-image-24867\" srcset=\"\/wp-content\/uploads\/2025\/05\/1V3A6800_DxO-1024x683.jpg 1024w, \/wp-content\/uploads\/2025\/05\/1V3A6800_DxO-300x200.jpg 300w, \/wp-content\/uploads\/2025\/05\/1V3A6800_DxO-768x512.jpg 768w, \/wp-content\/uploads\/2025\/05\/1V3A6800_DxO-1536x1024.jpg 1536w, \/wp-content\/uploads\/2025\/05\/1V3A6800_DxO-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2025\/05\/1V3A6804_DxO-1024x683.jpg\" alt=\"\" data-id=\"24868\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/1V3A6804_DxO-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=24868\" class=\"wp-image-24868\" srcset=\"\/wp-content\/uploads\/2025\/05\/1V3A6804_DxO-1024x683.jpg 1024w, \/wp-content\/uploads\/2025\/05\/1V3A6804_DxO-300x200.jpg 300w, \/wp-content\/uploads\/2025\/05\/1V3A6804_DxO-768x512.jpg 768w, \/wp-content\/uploads\/2025\/05\/1V3A6804_DxO-1536x1024.jpg 1536w, \/wp-content\/uploads\/2025\/05\/1V3A6804_DxO-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2025\/05\/1V3A6816_DxO-1024x683.jpg\" alt=\"\" data-id=\"24869\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/1V3A6816_DxO-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=24869\" class=\"wp-image-24869\" srcset=\"\/wp-content\/uploads\/2025\/05\/1V3A6816_DxO-1024x683.jpg 1024w, \/wp-content\/uploads\/2025\/05\/1V3A6816_DxO-300x200.jpg 300w, \/wp-content\/uploads\/2025\/05\/1V3A6816_DxO-768x512.jpg 768w, \/wp-content\/uploads\/2025\/05\/1V3A6816_DxO-1536x1024.jpg 1536w, \/wp-content\/uploads\/2025\/05\/1V3A6816_DxO-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2025\/05\/1V3A6852_DxO-1024x683.jpg\" alt=\"\" data-id=\"24870\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/1V3A6852_DxO-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=24870\" class=\"wp-image-24870\" srcset=\"\/wp-content\/uploads\/2025\/05\/1V3A6852_DxO-1024x683.jpg 1024w, \/wp-content\/uploads\/2025\/05\/1V3A6852_DxO-300x200.jpg 300w, \/wp-content\/uploads\/2025\/05\/1V3A6852_DxO-768x512.jpg 768w, \/wp-content\/uploads\/2025\/05\/1V3A6852_DxO-1536x1024.jpg 1536w, \/wp-content\/uploads\/2025\/05\/1V3A6852_DxO-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2025\/05\/1V3A6883_DxO-1024x683.jpg\" alt=\"\" data-id=\"24871\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/1V3A6883_DxO-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=24871\" class=\"wp-image-24871\" srcset=\"\/wp-content\/uploads\/2025\/05\/1V3A6883_DxO-1024x683.jpg 1024w, \/wp-content\/uploads\/2025\/05\/1V3A6883_DxO-300x200.jpg 300w, \/wp-content\/uploads\/2025\/05\/1V3A6883_DxO-768x512.jpg 768w, \/wp-content\/uploads\/2025\/05\/1V3A6883_DxO-1536x1024.jpg 1536w, \/wp-content\/uploads\/2025\/05\/1V3A6883_DxO-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"\/wp-content\/uploads\/2025\/05\/1V3A6914_DxO-1-1024x683.jpg\" alt=\"\" data-id=\"24872\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/1V3A6914_DxO-1-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=24872\" class=\"wp-image-24872\" srcset=\"\/wp-content\/uploads\/2025\/05\/1V3A6914_DxO-1-1024x683.jpg 1024w, \/wp-content\/uploads\/2025\/05\/1V3A6914_DxO-1-300x200.jpg 300w, \/wp-content\/uploads\/2025\/05\/1V3A6914_DxO-1-768x512.jpg 768w, \/wp-content\/uploads\/2025\/05\/1V3A6914_DxO-1-1536x1024.jpg 1536w, \/wp-content\/uploads\/2025\/05\/1V3A6914_DxO-1-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La 26 de ani de la prima dezvelire, basorelieful domnitorului \u0218tefan cel Mare \u0219i Sf\u00e2nt \u00ee\u0219i reg\u0103se\u0219te locul de onoare \u00een cadrul Academiei \u201e\u0218tefan cel Mare\u201d a MAI \u2013 o [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":24875,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"translation":{"provider":"WPGlobus","version":"2.12.2","language":"gb","enabled_languages":["ro","gb"],"languages":{"ro":{"title":true,"content":true,"excerpt":false},"gb":{"title":false,"content":false,"excerpt":false}}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/24857"}],"collection":[{"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/comments?post=24857"}],"version-history":[{"count":4,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/24857\/revisions"}],"predecessor-version":[{"id":24877,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/24857\/revisions\/24877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/media\/24875"}],"wp:attachment":[{"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/media?parent=24857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/categories?post=24857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/tags?post=24857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}