{"id":25213,"date":"2025-05-20T14:24:09","date_gmt":"2025-05-20T11:24:09","guid":{"rendered":"https:\/\/academy.police.md\/?p=25213"},"modified":"2025-09-24T16:08:53","modified_gmt":"2025-09-24T13:08:53","slug":"de-la-teorie-la-practica-studentii-academiei-in-vizita-la-centrul-de-instruire-continua-in-domeniul-electoral","status":"publish","type":"post","link":"https:\/\/www.academy.police.md\/gb\/de-la-teorie-la-practica-studentii-academiei-in-vizita-la-centrul-de-instruire-continua-in-domeniul-electoral","title":{"rendered":"De la teorie la practic\u0103: studen\u0163ii Academiei \u00een vizit\u0103 la Centrul de Instruire Continu\u0103 \u00een Domeniul Electoral"},"content":{"rendered":"\n<p>La data de 19 mai, un grup de studen\u021bi ai anului I de studiu, ciclul I &#8211; Domeniul general de studii ,,\u0218tiin\u021be administrative\u201d \u015fi ciclul II &#8211; Programul Drept, a vizitat Centrul de Instruire Continu\u0103 \u00een Domeniul Electoral (CICDE).<\/p>\n\n\n\n<p>\u00censo\u021bi\u021bi de asistentul universitar al Catedrei drept public, Dob\u0103 Olga, studen\u0163ii au fost familiariza\u021bi cu structura, atribu\u021biile \u0219i func\u021biile CICDE, cu instrumentele de instruire \u0219i educa\u021bie civic\u0103 dezvoltate de institu\u021bie. Tinerii au participat \u015fi la o sesiune informativ\u0103 sus\u021binut\u0103 de exper\u021bii centrului, care a inclus diverse teme, printre care: rolul angaja\u0163ilor MAI \u00een procesul electoral; atribu\u0163iile MAI \u00een perioada alegerilor; atribu\u0163iile MAI \u00een perioada \u00eentrunirilor pre-electorale; contraven\u0163ii \u015fi infrac\u0163iuni electorale; conlucrarea cu administra\u0163ia public\u0103 local\u0103.<\/p>\n\n\n\n<p>Activitatea s-a desf\u0103\u0219urat \u00een scopul aprofund\u0103rii a cuno\u0219tin\u021belor teoretice prin incursiuni &nbsp;practice \u00een domeniul sistemului electoral al Republicii Moldova, \u00een vederea form\u0103rii unei culturi juridico-electorale \u0219i consolid\u0103rii competen\u021belor profesionale ale viitorilor juri\u0219ti.<\/p>\n\n\n\n<p>Vizita a contribuit semnificativ la dezvoltarea unei perspective critice \u0219i interdisciplinare asupra proceselor democratice \u0219i a legitimit\u0103\u021bii electorale, consolid\u00e2nd, totodat\u0103, dialogul \u00eentre mediul academic \u0219i actorii institu\u021bionali relevan\u021bi.<\/p>\n\n\n\n<p>Vizitatorii au avut ocazia s\u0103 adreseze \u00eentreb\u0103ri speciali\u0219tilor din domeniu \u0219i s\u0103 exploreze, \u00eentr-un cadru practic, aspectele discutate \u00een cadrul orelor de curs. Evenimentul s-a finalizat cu rezolvarea unor spe\u0163e\/studii de caz elaborate pe baza temelor abordate.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"\/wp-content\/uploads\/2025\/05\/1-29-1024x768.jpg\" alt=\"\" data-id=\"25215\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/1-29-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=25215\" class=\"wp-image-25215\" srcset=\"\/wp-content\/uploads\/2025\/05\/1-29-1024x768.jpg 1024w, \/wp-content\/uploads\/2025\/05\/1-29-300x225.jpg 300w, \/wp-content\/uploads\/2025\/05\/1-29-768x576.jpg 768w, \/wp-content\/uploads\/2025\/05\/1-29-1536x1152.jpg 1536w, \/wp-content\/uploads\/2025\/05\/1-29-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"\/wp-content\/uploads\/2025\/05\/2-15-1024x768.jpg\" alt=\"\" data-id=\"25216\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/2-15-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=25216\" class=\"wp-image-25216\" srcset=\"\/wp-content\/uploads\/2025\/05\/2-15-1024x768.jpg 1024w, \/wp-content\/uploads\/2025\/05\/2-15-300x225.jpg 300w, \/wp-content\/uploads\/2025\/05\/2-15-768x576.jpg 768w, \/wp-content\/uploads\/2025\/05\/2-15-1536x1152.jpg 1536w, \/wp-content\/uploads\/2025\/05\/2-15-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"\/wp-content\/uploads\/2025\/05\/3-17-768x1024.jpg\" alt=\"\" data-id=\"25217\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/3-17-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=25217\" class=\"wp-image-25217\" srcset=\"\/wp-content\/uploads\/2025\/05\/3-17-768x1024.jpg 768w, \/wp-content\/uploads\/2025\/05\/3-17-225x300.jpg 225w, \/wp-content\/uploads\/2025\/05\/3-17-1152x1536.jpg 1152w, \/wp-content\/uploads\/2025\/05\/3-17-1536x2048.jpg 1536w, \/wp-content\/uploads\/2025\/05\/3-17-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"\/wp-content\/uploads\/2025\/05\/4-18-1024x768.jpg\" alt=\"\" data-id=\"25218\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/4-18-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=25218\" class=\"wp-image-25218\" srcset=\"\/wp-content\/uploads\/2025\/05\/4-18-1024x768.jpg 1024w, \/wp-content\/uploads\/2025\/05\/4-18-300x225.jpg 300w, \/wp-content\/uploads\/2025\/05\/4-18-768x576.jpg 768w, \/wp-content\/uploads\/2025\/05\/4-18-1536x1152.jpg 1536w, \/wp-content\/uploads\/2025\/05\/4-18-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"\/wp-content\/uploads\/2025\/05\/5-14-1024x768.jpg\" alt=\"\" data-id=\"25219\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/5-14-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=25219\" class=\"wp-image-25219\" srcset=\"\/wp-content\/uploads\/2025\/05\/5-14-1024x768.jpg 1024w, \/wp-content\/uploads\/2025\/05\/5-14-300x225.jpg 300w, \/wp-content\/uploads\/2025\/05\/5-14-768x576.jpg 768w, \/wp-content\/uploads\/2025\/05\/5-14-1536x1152.jpg 1536w, \/wp-content\/uploads\/2025\/05\/5-14-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"\/wp-content\/uploads\/2025\/05\/6-13-1024x768.jpg\" alt=\"\" data-id=\"25220\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/6-13-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=25220\" class=\"wp-image-25220\" srcset=\"\/wp-content\/uploads\/2025\/05\/6-13-1024x768.jpg 1024w, \/wp-content\/uploads\/2025\/05\/6-13-300x225.jpg 300w, \/wp-content\/uploads\/2025\/05\/6-13-768x576.jpg 768w, \/wp-content\/uploads\/2025\/05\/6-13-1536x1152.jpg 1536w, \/wp-content\/uploads\/2025\/05\/6-13-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"\/wp-content\/uploads\/2025\/05\/7-11-1024x768.jpg\" alt=\"\" data-id=\"25221\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/7-11-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=25221\" class=\"wp-image-25221\" srcset=\"\/wp-content\/uploads\/2025\/05\/7-11-1024x768.jpg 1024w, \/wp-content\/uploads\/2025\/05\/7-11-300x225.jpg 300w, \/wp-content\/uploads\/2025\/05\/7-11-768x576.jpg 768w, \/wp-content\/uploads\/2025\/05\/7-11-1536x1152.jpg 1536w, \/wp-content\/uploads\/2025\/05\/7-11-2048x1536.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"\/wp-content\/uploads\/2025\/05\/8-7-768x1024.jpg\" alt=\"\" data-id=\"25222\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/8-7-scaled.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=25222\" class=\"wp-image-25222\" srcset=\"\/wp-content\/uploads\/2025\/05\/8-7-768x1024.jpg 768w, \/wp-content\/uploads\/2025\/05\/8-7-225x300.jpg 225w, \/wp-content\/uploads\/2025\/05\/8-7-1152x1536.jpg 1152w, \/wp-content\/uploads\/2025\/05\/8-7-1536x2048.jpg 1536w, \/wp-content\/uploads\/2025\/05\/8-7-scaled.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><figcaption class=\"blocks-gallery-item__caption\">_reflectionremoval<\/figcaption><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La data de 19 mai, un grup de studen\u021bi ai anului I de studiu, ciclul I &#8211; Domeniul general de studii ,,\u0218tiin\u021be administrative\u201d \u015fi ciclul II &#8211; Programul Drept, a [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":25214,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"translation":{"provider":"WPGlobus","version":"2.12.2","language":"gb","enabled_languages":["ro","gb"],"languages":{"ro":{"title":true,"content":true,"excerpt":false},"gb":{"title":false,"content":false,"excerpt":false}}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/25213"}],"collection":[{"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/comments?post=25213"}],"version-history":[{"count":4,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/25213\/revisions"}],"predecessor-version":[{"id":27532,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/25213\/revisions\/27532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/media\/25214"}],"wp:attachment":[{"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/media?parent=25213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/categories?post=25213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/tags?post=25213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}