{"id":25573,"date":"2025-05-29T11:21:16","date_gmt":"2025-05-29T08:21:16","guid":{"rendered":"https:\/\/academy.police.md\/?p=25573"},"modified":"2025-05-29T11:45:49","modified_gmt":"2025-05-29T08:45:49","slug":"combaterea-amenintarilor-hibride-in-prim-planul-unui-curs-international","status":"publish","type":"post","link":"https:\/\/www.academy.police.md\/gb\/combaterea-amenintarilor-hibride-in-prim-planul-unui-curs-international","title":{"rendered":"Combaterea amenin\u021b\u0103rilor hibride, \u00een prim-planul unui curs interna\u021bional"},"content":{"rendered":"\n<p>\u00cen perioada 27-28 mai 2025, Academia ,,\u0218tefan cel Mare\u201d a MAI, a g\u0103zduit cursul interna\u021bional de instruire \u201eCombaterea amenin\u021b\u0103rilor hibride\u201d, organizat cu sprijinul Academiei de \u0218tiin\u021be ale Securit\u0103\u021bii din Estonia, al Organiza\u021biei pentru Dezvoltare, Securitate \u0219i Sustenabilitate (ODSS) \u0219i al Agen\u021biei Estone pentru Cooperare \u0219i Dezvoltare (ESTDEV).<\/p>\n\n\n\n<p>Programul de formare a reunit exper\u021bi de marc\u0103 \u00een domeniul securit\u0103\u021bii \u0219i ap\u0103r\u0103rii, \u00een cadrul c\u0103ruia, au abordat subiecte esen\u021biale precum recunoa\u0219terea, prevenirea \u0219i combaterea amenin\u021b\u0103rilor hibride. Printre temele discutate s-au num\u0103rat dezinformarea, ingerin\u021bele str\u0103ine, atacurile cibernetice \u0219i influen\u021bele strategice exercitate \u00een spa\u021biul public.<\/p>\n\n\n\n<p>Totodat\u0103, agenda acestei edi\u021bii a inclus \u015fi participarea unor exper\u021bi interna\u021bionali de prestigiu, precum reprezentan\u0163i ai EUPM \u0219i Academia Folke Bernadotte, recunoscu\u021bi pentru expertiza lor \u00een domeniul amenin\u021b\u0103rilor hibride, care \u0219i-au exprimat deschiderea fa\u021b\u0103 de ini\u021bierea unor direc\u021bii de cooperare cu institu\u021bia noastr\u0103.<\/p>\n\n\n\n<p>Cursul s-a desf\u0103\u0219urat \u00eentr-un format interactiv, promov\u00e2nd schimbul de bune practici \u0219i consolidarea unei re\u021bele profesionale \u00eentre reprezentan\u021bi ai autorit\u0103\u021bilor na\u021bionale \u0219i parteneri interna\u021bionali.<\/p>\n\n\n\n<p>Aceast\u0103 ini\u021biativ\u0103 reprezint\u0103 un pas important \u00een \u00eent\u0103rirea capacit\u0103\u021bilor na\u021bionale \u0219i regionale de a r\u0103spunde eficient provoc\u0103rilor complexe din domeniul securit\u0103\u021bii contemporane.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"561\" src=\"\/wp-content\/uploads\/2025\/05\/IMG_6061-1024x561.jpg\" alt=\"\" data-id=\"25575\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/IMG_6061.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=25575\" class=\"wp-image-25575\" srcset=\"\/wp-content\/uploads\/2025\/05\/IMG_6061-1024x561.jpg 1024w, \/wp-content\/uploads\/2025\/05\/IMG_6061-300x164.jpg 300w, \/wp-content\/uploads\/2025\/05\/IMG_6061-768x421.jpg 768w, \/wp-content\/uploads\/2025\/05\/IMG_6061-1536x842.jpg 1536w, \/wp-content\/uploads\/2025\/05\/IMG_6061.jpg 1985w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"611\" src=\"\/wp-content\/uploads\/2025\/05\/IMG_6066-1024x611.jpg\" alt=\"\" data-id=\"25576\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/IMG_6066.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=25576\" class=\"wp-image-25576\" srcset=\"\/wp-content\/uploads\/2025\/05\/IMG_6066-1024x611.jpg 1024w, \/wp-content\/uploads\/2025\/05\/IMG_6066-300x179.jpg 300w, \/wp-content\/uploads\/2025\/05\/IMG_6066-768x458.jpg 768w, \/wp-content\/uploads\/2025\/05\/IMG_6066-1536x917.jpg 1536w, \/wp-content\/uploads\/2025\/05\/IMG_6066.jpg 1985w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"675\" src=\"\/wp-content\/uploads\/2025\/05\/IMG_6083-1024x675.jpg\" alt=\"\" data-id=\"25577\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/IMG_6083.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=25577\" class=\"wp-image-25577\" srcset=\"\/wp-content\/uploads\/2025\/05\/IMG_6083-1024x675.jpg 1024w, \/wp-content\/uploads\/2025\/05\/IMG_6083-300x198.jpg 300w, \/wp-content\/uploads\/2025\/05\/IMG_6083-768x506.jpg 768w, \/wp-content\/uploads\/2025\/05\/IMG_6083-1536x1013.jpg 1536w, \/wp-content\/uploads\/2025\/05\/IMG_6083.jpg 1985w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"541\" src=\"\/wp-content\/uploads\/2025\/05\/IMG_6102-1024x541.jpg\" alt=\"\" data-id=\"25578\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/IMG_6102.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=25578\" class=\"wp-image-25578\" srcset=\"\/wp-content\/uploads\/2025\/05\/IMG_6102-1024x541.jpg 1024w, \/wp-content\/uploads\/2025\/05\/IMG_6102-300x159.jpg 300w, \/wp-content\/uploads\/2025\/05\/IMG_6102-768x406.jpg 768w, \/wp-content\/uploads\/2025\/05\/IMG_6102-1536x812.jpg 1536w, \/wp-content\/uploads\/2025\/05\/IMG_6102.jpg 1985w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"529\" src=\"\/wp-content\/uploads\/2025\/05\/IMG_6110-1024x529.jpg\" alt=\"\" data-id=\"25579\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/IMG_6110.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=25579\" class=\"wp-image-25579\" srcset=\"\/wp-content\/uploads\/2025\/05\/IMG_6110-1024x529.jpg 1024w, \/wp-content\/uploads\/2025\/05\/IMG_6110-300x155.jpg 300w, \/wp-content\/uploads\/2025\/05\/IMG_6110-768x397.jpg 768w, \/wp-content\/uploads\/2025\/05\/IMG_6110-1536x794.jpg 1536w, \/wp-content\/uploads\/2025\/05\/IMG_6110.jpg 1985w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"502\" src=\"\/wp-content\/uploads\/2025\/05\/IMG_6115-1024x502.jpg\" alt=\"\" data-id=\"25580\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/IMG_6115.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=25580\" class=\"wp-image-25580\" srcset=\"\/wp-content\/uploads\/2025\/05\/IMG_6115-1024x502.jpg 1024w, \/wp-content\/uploads\/2025\/05\/IMG_6115-300x147.jpg 300w, \/wp-content\/uploads\/2025\/05\/IMG_6115-768x377.jpg 768w, \/wp-content\/uploads\/2025\/05\/IMG_6115-1536x754.jpg 1536w, \/wp-content\/uploads\/2025\/05\/IMG_6115.jpg 1985w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"525\" src=\"\/wp-content\/uploads\/2025\/05\/IMG_6209-1024x525.jpg\" alt=\"\" data-id=\"25581\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/IMG_6209.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=25581\" class=\"wp-image-25581\" srcset=\"\/wp-content\/uploads\/2025\/05\/IMG_6209-1024x525.jpg 1024w, \/wp-content\/uploads\/2025\/05\/IMG_6209-300x154.jpg 300w, \/wp-content\/uploads\/2025\/05\/IMG_6209-768x394.jpg 768w, \/wp-content\/uploads\/2025\/05\/IMG_6209-1536x788.jpg 1536w, \/wp-content\/uploads\/2025\/05\/IMG_6209.jpg 1985w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"491\" src=\"\/wp-content\/uploads\/2025\/05\/IMG_6216-1024x491.jpg\" alt=\"\" data-id=\"25582\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/IMG_6216.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=25582\" class=\"wp-image-25582\" srcset=\"\/wp-content\/uploads\/2025\/05\/IMG_6216-1024x491.jpg 1024w, \/wp-content\/uploads\/2025\/05\/IMG_6216-300x144.jpg 300w, \/wp-content\/uploads\/2025\/05\/IMG_6216-768x368.jpg 768w, \/wp-content\/uploads\/2025\/05\/IMG_6216-1536x737.jpg 1536w, \/wp-content\/uploads\/2025\/05\/IMG_6216.jpg 1985w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"468\" src=\"\/wp-content\/uploads\/2025\/05\/IMG_6311-1-1024x468.jpg\" alt=\"\" data-id=\"25583\" data-full-url=\"\/wp-content\/uploads\/2025\/05\/IMG_6311-1.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=25583\" class=\"wp-image-25583\" srcset=\"\/wp-content\/uploads\/2025\/05\/IMG_6311-1-1024x468.jpg 1024w, \/wp-content\/uploads\/2025\/05\/IMG_6311-1-300x137.jpg 300w, \/wp-content\/uploads\/2025\/05\/IMG_6311-1-768x351.jpg 768w, \/wp-content\/uploads\/2025\/05\/IMG_6311-1-1536x702.jpg 1536w, \/wp-content\/uploads\/2025\/05\/IMG_6311-1.jpg 1985w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00cen perioada 27-28 mai 2025, Academia ,,\u0218tefan cel Mare\u201d a MAI, a g\u0103zduit cursul interna\u021bional de instruire \u201eCombaterea amenin\u021b\u0103rilor hibride\u201d, organizat cu sprijinul Academiei de \u0218tiin\u021be ale Securit\u0103\u021bii din Estonia, [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":25574,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"translation":{"provider":"WPGlobus","version":"2.12.2","language":"gb","enabled_languages":["ro","gb"],"languages":{"ro":{"title":true,"content":true,"excerpt":false},"gb":{"title":false,"content":false,"excerpt":false}}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/25573"}],"collection":[{"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/comments?post=25573"}],"version-history":[{"count":6,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/25573\/revisions"}],"predecessor-version":[{"id":25599,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/25573\/revisions\/25599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/media\/25574"}],"wp:attachment":[{"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/media?parent=25573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/categories?post=25573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/tags?post=25573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}