{"id":29505,"date":"2025-12-11T15:59:40","date_gmt":"2025-12-11T13:59:40","guid":{"rendered":"https:\/\/academy.police.md\/?p=29505"},"modified":"2025-12-12T07:54:03","modified_gmt":"2025-12-12T05:54:03","slug":"solidaritate-si-valori-umane-studentii-academiei-contribuie-la-sprijinirea-persoanelor-cu-dizabilitati","status":"publish","type":"post","link":"https:\/\/www.academy.police.md\/gb\/solidaritate-si-valori-umane-studentii-academiei-contribuie-la-sprijinirea-persoanelor-cu-dizabilitati","title":{"rendered":"Solidaritate \u0219i valori umane: studen\u021bii Academiei contribuie la sprijinirea persoanelor cu dizabilit\u0103\u021bi"},"content":{"rendered":"\n<p>Recent, studen\u021bii din cadrul Academiei \u201e\u0218tefan cel Mare\u201d a MAI s-au implicat activ \u00een campania de binefacere organizat\u0103 cu prilejul Zilei Interna\u021bionale a Persoanelor cu Dizabilit\u0103\u021bi.<\/p>\n\n\n\n<p>Sub coordonarea \u0219efului sec\u021biei, \u00eentregul efectiv de studen\u021bi &#8211; \u0219i-a exprimat disponibilitatea de a contribui benevol la sprijinirea persoanelor vulnerabile. Studen\u021bilor le-a fost prezentat\u0103 esen\u021ba campaniei \u0219i modul \u00een care pot sus\u021bine aceast\u0103 ini\u021biativ\u0103 social\u0103, fiind subliniat caracterul voluntar al particip\u0103rii.<\/p>\n\n\n\n<p>Majoritatea studen\u021bilor au decis s\u0103 se al\u0103ture ac\u021biunii caritabile, \u00een semn de solidaritate cu persoanele aflate \u00een situa\u021bii de vulnerabilitate. Contribu\u021biile au fost direc\u021bionate c\u0103tre Centrul de Plasament pentru Persoane V\u00e2rstnice \u0219i Persoane cu Dizabilit\u0103\u021bi din municipiul Chi\u0219in\u0103u.<\/p>\n\n\n\n<p>Prin aceast\u0103 contribu\u021bie, studen\u021bii au demonstrat responsabilitate, empatie \u0219i spirit civic, reconfirm\u00e2nd valorile pe care Academia \u201e\u0218tefan cel Mare\u201d a MAI le promoveaz\u0103 \u00een formarea viitorilor profesioni\u0219ti ai structurilor de ordine public\u0103.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"\/wp-content\/uploads\/2025\/12\/1-40-1024x768.jpg\" alt=\"\" data-id=\"29507\" data-full-url=\"\/wp-content\/uploads\/2025\/12\/1-40.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=29507\" class=\"wp-image-29507\" srcset=\"\/wp-content\/uploads\/2025\/12\/1-40-1024x768.jpg 1024w, \/wp-content\/uploads\/2025\/12\/1-40-300x225.jpg 300w, \/wp-content\/uploads\/2025\/12\/1-40-768x576.jpg 768w, \/wp-content\/uploads\/2025\/12\/1-40.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155400_703-768x1024.jpg\" alt=\"\" data-id=\"29508\" data-full-url=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155400_703.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=29508\" class=\"wp-image-29508\" srcset=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155400_703-768x1024.jpg 768w, \/wp-content\/uploads\/2025\/12\/IMG_20251211_155400_703-225x300.jpg 225w, \/wp-content\/uploads\/2025\/12\/IMG_20251211_155400_703.jpg 960w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155411_379-768x1024.jpg\" alt=\"\" data-id=\"29509\" data-full-url=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155411_379.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=29509\" class=\"wp-image-29509\" srcset=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155411_379-768x1024.jpg 768w, \/wp-content\/uploads\/2025\/12\/IMG_20251211_155411_379-225x300.jpg 225w, \/wp-content\/uploads\/2025\/12\/IMG_20251211_155411_379.jpg 960w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155415_193-768x1024.jpg\" alt=\"\" data-id=\"29510\" data-full-url=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155415_193.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=29510\" class=\"wp-image-29510\" srcset=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155415_193-768x1024.jpg 768w, \/wp-content\/uploads\/2025\/12\/IMG_20251211_155415_193-225x300.jpg 225w, \/wp-content\/uploads\/2025\/12\/IMG_20251211_155415_193.jpg 960w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155431_026-768x1024.jpg\" alt=\"\" data-id=\"29511\" data-full-url=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155431_026.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=29511\" class=\"wp-image-29511\" srcset=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155431_026-768x1024.jpg 768w, \/wp-content\/uploads\/2025\/12\/IMG_20251211_155431_026-225x300.jpg 225w, \/wp-content\/uploads\/2025\/12\/IMG_20251211_155431_026.jpg 960w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155437_712-768x1024.jpg\" alt=\"\" data-id=\"29512\" data-full-url=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155437_712.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=29512\" class=\"wp-image-29512\" srcset=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155437_712-768x1024.jpg 768w, \/wp-content\/uploads\/2025\/12\/IMG_20251211_155437_712-225x300.jpg 225w, \/wp-content\/uploads\/2025\/12\/IMG_20251211_155437_712.jpg 960w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155444_215-768x1024.jpg\" alt=\"\" data-id=\"29513\" data-full-url=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155444_215.jpg\" data-link=\"https:\/\/academy.police.md\/?attachment_id=29513\" class=\"wp-image-29513\" srcset=\"\/wp-content\/uploads\/2025\/12\/IMG_20251211_155444_215-768x1024.jpg 768w, \/wp-content\/uploads\/2025\/12\/IMG_20251211_155444_215-225x300.jpg 225w, \/wp-content\/uploads\/2025\/12\/IMG_20251211_155444_215.jpg 960w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Recent, studen\u021bii din cadrul Academiei \u201e\u0218tefan cel Mare\u201d a MAI s-au implicat activ \u00een campania de binefacere organizat\u0103 cu prilejul Zilei Interna\u021bionale a Persoanelor cu Dizabilit\u0103\u021bi. Sub coordonarea \u0219efului sec\u021biei, [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":29506,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"translation":{"provider":"WPGlobus","version":"2.12.2","language":"gb","enabled_languages":["ro","gb"],"languages":{"ro":{"title":true,"content":true,"excerpt":false},"gb":{"title":false,"content":false,"excerpt":false}}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/29505"}],"collection":[{"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/comments?post=29505"}],"version-history":[{"count":8,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/29505\/revisions"}],"predecessor-version":[{"id":29531,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/posts\/29505\/revisions\/29531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/media\/29506"}],"wp:attachment":[{"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/media?parent=29505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/categories?post=29505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.academy.police.md\/gb\/wp-json\/wp\/v2\/tags?post=29505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}